{"id":227,"count":1,"description":"","link":"https:\/\/laurencecoffee.id\/berita\/tag\/resep-ceker-pedas-manis\/","name":"resep-ceker-pedas-manis","slug":"resep-ceker-pedas-manis","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/laurencecoffee.id\/berita\/wp-json\/wp\/v2\/tags\/227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurencecoffee.id\/berita\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/laurencecoffee.id\/berita\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/laurencecoffee.id\/berita\/wp-json\/wp\/v2\/posts?tags=227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}